{"id":6147,"date":"2023-04-04T07:32:23","date_gmt":"2023-04-04T07:32:23","guid":{"rendered":"https:\/\/www.teleboy.ch\/magazin\/?p=6147"},"modified":"2023-04-17T09:44:01","modified_gmt":"2023-04-17T09:44:01","slug":"die-besten-thriller-mit-imdb-topbewertung","status":"publish","type":"post","link":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/","title":{"rendered":"Die besten Thriller mit IMDb-Topbewertung"},"content":{"rendered":"\n<p>In unserem eigenen Leben k\u00f6nnen wir auf handfeste Bedrohungen und lebensgef\u00e4hrliche Situationen gut und gerne verzichten. Im Kino aber geben wir uns ihnen bereitwillig hin. Vor allem Thriller-Stoffe sollen unseren Puls nach oben treiben, was immer mal wieder spektakul\u00e4r gut gelingt. Einige der auf der Filmplattform <a href=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/imdb-topfilme-die-besten-filme-aller-zeiten\/\">IMDb<\/a> am besten bewerteten Leinwandnervenkitzler m\u00f6chten wir euch ans Herz legen. Auf dass das Adrenalin in Wallung geraten kann!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-das-fenster-zum-hof-1954-hitchcock-fuhrt-unsere-schaulust-vor\"><strong>\u00abDas Fenster zum Hof\u00bb (1954): Hitchcock f\u00fchrt unsere Schaulust vor<\/strong><\/h2>\n\n\n\n<p>Als \u00abmaster of suspense\u00bb hat Alfred Hitchcock viele einflussreiche Thriller-Werke gedreht. Wohl keines spiegelt jedoch die voyeuristische Position der Kinozuschauer:innen so gekonnt wie \u00abDas Fenster zum Hof\u00bb. James Stewart spielt darin einen Fotojournalisten, der nach einem Beinbruch vor\u00fcbergehend an den Rollstuhl gefesselt ist und seine Wohnung nicht verlassen kann. Um sich abzulenken, beobachtet er ausgiebig den Alltag seiner Nachbarn. Irgendwann glaubt er, dass in unmittelbarer N\u00e4he ein Mord geschehen sein k\u00f6nnte. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Fenster-zum-Hof\u00a9-Paramount-Pictures-1024x672.jpeg\" alt=\"Thriller mit sehr guten IMDb-Bewertungen\" class=\"wp-image-6157\" width=\"840\" height=\"551\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Fenster-zum-Hof\u00a9-Paramount-Pictures-1024x672.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Fenster-zum-Hof\u00a9-Paramount-Pictures-300x197.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Fenster-zum-Hof\u00a9-Paramount-Pictures-768x504.jpeg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Fenster-zum-Hof\u00a9-Paramount-Pictures.jpeg 1064w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><figcaption class=\"wp-element-caption\">Die besten Thriller mit IMDb-Topbewertung: Alfred Hitchcocks \u00abDas Fenster zum Hof\u00bb \u00a9Paramount Pictures<\/figcaption><\/figure>\n\n\n\n<p>Spannung bezieht Hitchcocks Klassiker nicht nur aus der Frage, ob die Hauptfigur richtigliegt. Auch seine k\u00f6rperliche Einschr\u00e4nkung tr\u00e4gt entscheidend zur nervenaufreibenden Wirkung bei. W\u00e4hrend die Kamera Stewarts Fotoreporter fast nie verl\u00e4sst, macht uns der Regisseur die Verbindungen zwischen der Schaulust des Protagonisten und unserer eigenen Neugier bewusst. Genau wie er werfen wir einen Blick in eine andere Welt, hoffen darauf, etwas Ungew\u00f6hnliches zu sehen, und k\u00f6nnen unsere Augen nicht vom Geschehen abwenden. Der einzige Unterschied: Der Rollstuhlvoyeur bringt sich wirklich in grosse Gefahr. Wir hingegen k\u00f6nnen alles entspannt aus der Sicherheit des Kinosessels oder des heimischen Sofas verfolgen. Mit einer <strong><a href=\"https:\/\/www.imdb.com\/title\/tt0047396\/?ref_=nv_sr_srsg_0\">IMDb-Wertung von 8,5 Sternen<\/a><\/strong> geh\u00f6rt der Hitchcock-Klassiker zu den besten Thrillern aller Zeiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-chinatown-1974-jack-nicholson-als-privatdetektiv-in-gefahr\"><strong>\u00abChinatown\u00bb (1974): Jack Nicholson als Privatdetektiv in Gefahr<\/strong><\/h2>\n\n\n\n<p>Roman Pola\u0144skis im Jahr 1937 angesiedelte Hommage an den Film noir, die d\u00fcsteren, nihilistischen US-amerikanischen Spannungsfilme der Nachkriegszeit, ist nat\u00fcrlich eine Detektiv- und Kriminalgeschichte. Immerhin steht mit Jack Nicholsons J. J. Gittes ein l\u00e4ssiger Privatermittler im Zentrum des Geschehens. Als Thriller qualifiziert sich \u00abChinatown\u00bb allerdings ebenfalls, da der Schn\u00fcffler bei seinen Nachforschungen in einem mysteri\u00f6sen Mordfall immer wieder selbst in Gefahr ger\u00e4t. Robert Townes verschlungenes, nahezu perfekt komponiertes Drehbuch, das sich auch um ein schmerzhaft-bedr\u00fcckendes Inzestdrama dreht, erhielt zu Recht einen Oscar. Kinolegende John Huston hat als fieser Patriarch einen beunruhigend-abgr\u00fcndigen Auftritt. Und ganz nebenbei erfahren wir einiges \u00fcber die hart gef\u00fchrten Konflikte \u00fcber die Wasserrechte rund um Los Angeles.&nbsp;Die besten Thriller aller Zeiten: Auf diese Liste geh\u00f6rt \u00abChinatown\u00bb mit einer <strong><a href=\"https:\/\/www.imdb.com\/title\/tt0071315\/?ref_=nv_sr_srsg_0\">IMDb-Wertung von 8,2 Sternen<\/a><\/strong> auf jeden Fall.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Chinatown_Cineman.jpeg\" alt=\"\" class=\"wp-image-6158\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Chinatown_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Chinatown_Cineman-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Chinatown_Cineman-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00abChinatown\u00bb geh\u00f6rt zu den Thrillern mit IMDb-Topbewertung. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sieben-1995-david-finchers-apokalyptische-serienkillerhatz\"><strong>\u00abSieben\u00bb (1995): David Finchers apokalyptische Serienkillerhatz<\/strong><\/h2>\n\n\n\n<p>\u00abDas Schweigen der L\u00e4mmer\u00bb (1991) und \u00abSieben\u00bb sind die beiden Filme, die das Gerne des Serienkillerthrillers im Mainstream salonf\u00e4hig machten. Vier Jahre nach Anthony Hopkins\u2018 fr\u00f6stelnd intensiver Darbietung als durchtriebener Psychiater Dr. Hannibal Lecter schickte David Fincher Brad Pitt und Morgan Freeman auf die Jagd nach einem wahnsinnigen M\u00f6rder, der sich bei seinen grotesk in Szene gesetzten Taten an den sieben Tods\u00fcnden orientiert. Das Katz-und-Maus-Spiel steuert auf einen wahrlich ersch\u00fctternden Showdown zu, den man so schnell nicht mehr aus dem Kopf bekommt. Was den Film besonders auszeichnet, ist seine allumfassende Hoffnungslosigkeit. Passend zu den religi\u00f6s aufgeladenen Verbrechen scheint das Setting, eine namenlos bleibende US-Grossstadt, in apokalyptischen Regeng\u00fcssen zu ersaufen. Viel d\u00fcsterer als in den Bildern von Kameramann Darius Khondji ging es im Hollywood-Kino seither nur noch selten zu. Mit einer <strong><a href=\"https:\/\/www.imdb.com\/title\/tt0114369\/?ref_=nv_sr_srsg_1\">IMDb-Wertung von 8,6 Sternen<\/a><\/strong> \u00fcberzeugt der Thriller auf allen Ebenen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Sieben_Cineman.jpeg\" alt=\"\" class=\"wp-image-6160\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Sieben_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Sieben_Cineman-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Sieben_Cineman-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Mit einer Bewertung von 8,6 Sternen geh\u00f6rt \u00abSieben\u00bb eindeutig auf die Liste der besten Thriller. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-die-ublichen-verdachtigen-1995-der-inbegriff-des-mindfuck-films\"><strong>\u00abDie \u00fcblichen Verd\u00e4chtigen\u00bb (1995): Der Inbegriff des \u00abMindfuck\u00bb-Films<\/strong><\/h2>\n\n\n\n<p>Sie f\u00fchren das Publikum geschickt auf falsche F\u00e4hrten und ziehen uns am Ende den Boden unter den F\u00fcssen weg. Dann, wenn klar wird, dass vieles, was wir zuvor gezeigt bekommen haben, anders gesehen werden muss. \u00abMindfuck\u00bb-Filme demonstrieren die Macht der Manipulation und sind oft von ihrer grossen, \u00fcberraschenden Schlusspointe aus gedacht. Ein prominentes Beispiel dieser vor allem im Spannungskino sehr beliebten Spielart ist der mit Filmzitaten gespickte Crime-Thriller \u00abDie \u00fcblichen Verd\u00e4chtigen\u00bb, in dem ein Zollinspektor (Chazz Palminteri) nach einer verheerenden Schiesserei im Hafen von San Pedro einen der Beteiligten (Kevin Spacey) befragt. Dessen Schilderungen werden in virtuos arrangierten R\u00fcckblenden bebildert. Im Finale steht dann, wie es sich f\u00fcr einen Last-Act-Twist-Beitrag geh\u00f6rt, eine faustdicke \u00dcberraschung, die uns die Verf\u00fchrungsk\u00fcnste des Filmmediums eindr\u00fccklich vor Augen f\u00fchrt. Der Thriller mit \u00dcberraschungseffekt \u00fcberzeugt Zuschauer:innen weltweit mit einer <strong><a href=\"https:\/\/www.imdb.com\/title\/tt0114814\/?ref_=nv_sr_srsg_0\">IMDb-Wertung von 8,5 Sternen<\/a><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Die-ueblichen-Verdaechtigen_\u00a9-Columbia-TriStar-Pictures.jpeg\" alt=\"\" class=\"wp-image-6161\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Die-ueblichen-Verdaechtigen_\u00a9-Columbia-TriStar-Pictures.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Die-ueblichen-Verdaechtigen_\u00a9-Columbia-TriStar-Pictures-300x198.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Die-ueblichen-Verdaechtigen_\u00a9-Columbia-TriStar-Pictures-768x507.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ein erstklassiger Thriller mit viel Spannung und \u00fcberraschenden Wendungen. \u00a9Columbia TriStar Pictures<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-memento-2000-christopher-nolans-vertracktes-filmpuzzle\"><strong>\u00abMemento\u00bb (2000): Christopher Nolans vertracktes Filmpuzzle<\/strong><\/h2>\n\n\n\n<p>Selten gehen filmische Form und filmischer Inhalt derart Hand in Hand wie in Christopher Nolans Hirnverdreher \u00abMemento\u00bb, der in seiner ungew\u00f6hnlichen Erz\u00e4hlstruktur die br\u00fcchige Wahrnehmung seines Protagonisten greifbar macht. Nach einem Einbruch, bei dem seine Ehefrau get\u00f6tet wurde, leidet Leonard (Guy Pearce) an einer sogenannten anterograden Amnesie, kann neue Informationen nur f\u00fcr einen sehr kurzen Zeitraum speichern und f\u00fchlt sich danach in der jeweiligen Situation v\u00f6llig verloren. Mithilfe eint\u00e4towierter Hinweise und Polaroids von vermeintlich wichtigen Orten und Personen versucht er dennoch, den M\u00f6rder seiner Gattin zu finden. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"699\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento_Cineman.jpeg\" alt=\"Die besten Thriller mit IMDb-Topbewertung: Momento\" class=\"wp-image-6163\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento_Cineman-300x205.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento_Cineman-768x524.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Christopher Nolans \u00abMemento\u00bb ist ein meisterlicher Thriller mit Topbewertung. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<p>Unterteilt ist der Thriller in zwei Handlungsf\u00e4den. Der in schwarz-weiss gehaltene Strang l\u00e4uft chronologisch vorw\u00e4rts ab, w\u00e4hrend der zweite farbig ausf\u00e4llt und chronologisch r\u00fcckw\u00e4rtslaufend aufgebaut ist. Die Verwirrung, die den Wahrheitssucher aufgrund seines Krankheitsbildes immer wieder bef\u00e4llt, \u00fcbertr\u00e4gt sich direkt auf den Zuschauer und stellt Leonards Zuverl\u00e4ssigkeit mehr und mehr in Frage. Wer komplexe Puzzlespiele liebt, darf sich \u00abMemento\u00bb nicht entgehen lassen! Nolans packendes Werk bekommt eine <a href=\"https:\/\/www.imdb.com\/title\/tt0209144\/?ref_=nv_sr_srsg_0\">I<strong>MDb-Wertung von 8,4 Sternen<\/strong><\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-city-of-god-2002-schonungsloser-einblick-in-das-favela-leben\"><strong>\u00abCity of God\u00bb (2002): Schonungsloser Einblick in das Favela-Leben<\/strong><\/h2>\n\n\n\n<p>Der von Fernando Meirelles und K\u00e1tia Lund inszenierte Film operiert an den Schnittstellen zwischen Drama, Krimi und Drogenthriller. Optisch und akustisch wird uns einiges geboten, entfaltet die von wahren Ereignissen inspirierte Romanadaption eine enorme Wucht. Im Mittelpunkt der stark subjektiv gepr\u00e4gten Handlung stehen drei Stationen eines brutalen Drogenkriegs unter den jungen Bewohner:innen der titelgebenden Favela am Rande Rio de Janeiros. Authentisch f\u00fchlt sich der preisgekr\u00f6nte Streifen nicht nur deshalb an, weil er viele unterschiedliche Perspektiven aufgreift und ein gutes Auge f\u00fcr die sozialen Gegebenheiten in der Barackensiedlung hat. Entscheidend f\u00fcr die Glaubw\u00fcrdigkeit der Geschichte ist auch die Besetzung der meisten Rollen mit Laiendarsteller:innen, Jugendlichen, die selbst aus Elendsviertel wie der \u00abStadt Gottes\u00bb kommen. Der Film bekommt bei <strong><a href=\"https:\/\/www.imdb.com\/title\/tt0317248\/?ref_=nv_sr_srsg_0\">IMDb eine Wertung von 8,6 Sternen<\/a>.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/City-of-God_Cineman-1024x678.jpeg\" alt=\"Die besten Thriller mit IMDb-Topbewerung: City of God\" class=\"wp-image-6166\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/City-of-God_Cineman-1024x678.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/City-of-God_Cineman-300x199.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/City-of-God_Cineman-768x508.jpeg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/City-of-God_Cineman.jpeg 1035w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Drama, Krimi und Drogenthriller. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-oldboy-2003-beinharte-rachefantasie-aus-sudkorea\"><strong>\u00abOldboy\u00bb (2003): Beinharte Rachefantasie aus S\u00fcdkorea<\/strong><\/h2>\n\n\n\n<p>Basierend auf der gleichnamigen Manga-Vorlage skizziert Park Chan-wook in \u00abOldboy\u00bb die Suche eines 15 Jahre lang gefangen gehaltenen Gesch\u00e4ftsmannes (Choi Min-sik) nach seinen Peinigern. Trotz vieler ultrabrutaler, schwer ertr\u00e4glicher Szenen erweist sich die fragmentarisch erz\u00e4hlte, durchaus komplex gebaute Rachegeschichte als stilistisch brillante Meditation \u00fcber die Sinnhaftigkeit von Selbstjustiz. Zwei Stunden lang werden wir an emotionale Grenzen gef\u00fchrt, bleibt uns nichts erspart. Und doch ragt der Film aus dem Subgenre des oft stumpfsinnigen Vergeltungskinos heraus. Wie viel Qualit\u00e4t in Parks albtraumhaftem Thriller steckt, zeigt nicht zuletzt der direkte Vergleich mit dem unvermeidlichen US-Remake, das 2013 das Licht der Welt erblickte. Spike Lees Version mit Josh Brolin in der Hauptrolle zieht klar den K\u00fcrzeren, da sie bei weitem nicht die inszenatorische Finesse des s\u00fcdkoreanischen Originals erreicht. Der Rachezug bekommt eine <a href=\"https:\/\/www.imdb.com\/title\/tt0364569\/?ref_=nv_sr_srsg_0\"><strong>IMDb-Wertung von 8,4 Sternen<\/strong>.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Oldboy_capelight-pictures.jpeg\" alt=\"Die besten Thriller mit IMDb-Topbewertung: Oldboy\" class=\"wp-image-6168\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Oldboy_capelight-pictures.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Oldboy_capelight-pictures-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Oldboy_capelight-pictures-768x511.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ein packender Rachezug: \u00abOldboy\u00bb ist ein Thriller mit Finesse. \u00a9capelight pictures<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-das-leben-der-anderen-2006-oscar-triumph-mit-ddr-thriller\"><strong>\u00abDas Leben der Anderen\u00bb (2006): Oscar-Triumph mit DDR-Thriller<\/strong><\/h2>\n\n\n\n<p>Kompetent gemachte deutsche Vergangenheitsbew\u00e4ltigung funktioniert auf internationalem Parkett oft erstaunlich gut. So auch im Fall von Florian Henckel von Donnersmarcks Thriller-Drama \u00abDas Leben der Anderen\u00bb, in dem Ulrich M\u00fche mit eindringlicher Zur\u00fcckhaltung einen Abh\u00f6rspezialisten der Stasi gibt, der Mitte der 1980er Jahre einen gefeierten Dramatiker regimekritische \u00c4usserungen nachweisen soll. W\u00e4hrend seiner Arbeit zweifelt allerdings er zunehmend am Unterdr\u00fcckungs- und \u00dcberwachungssystem, dem er bislang so treu gedient hat. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Leben-der-Anderen_Cineman.jpeg\" alt=\"Die besten Thriller mit IMDb-Topbewertung: Das Leben der anderen\" class=\"wp-image-6169\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Leben-der-Anderen_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Leben-der-Anderen_Cineman-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Das-Leben-der-Anderen_Cineman-768x511.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Erstklassiger Thriller mit Oscar: \u00abDas Leben der Anderen\u00bb. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<p>Bei den Oscars 2007 erhielt der Film die Troph\u00e4e f\u00fcr das beste fremdsprachige Werk. Eine nicht unverdiente Auszeichnung, weil es dem Regisseur und Drehbuchautor gelingt, ausgehend von Einzelschicksalen spannungsreich von den unmenschlichen Mechanismen des DDR-Apparates zu erz\u00e4hlen. Manchen melodramatischen Schn\u00f6rkel kann man kritisch sehen. Florian Henckel von Donnersmarck zieht uns aber dennoch vom Start weg in die Geschichte hinein und beschw\u00f6rt mit einer vor allem von Graut\u00f6nen bestimmten Bild\u00e4sthetik ein handfestes Gef\u00fchl der Trostlosigkeit. Einer der wenigen deutschen Thriller, der es in die Liste der besten Thriller mit einer <strong><a href=\"https:\/\/www.imdb.com\/title\/tt0405094\/?ref_=nv_sr_srsg_0\">IMDb-Wertung von 8,4 Sternen<\/a><\/strong> schafft.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-thriller-mit-imdb-topbewertung-bei-teleboy\">Thriller mit IMDb-Topbewertung bei Teleboy<\/h2>\n\n\n\n<p>Eine gem\u00fctliche Sitzm\u00f6glichkeit, ein paar Snacks und ein guter Thriller sind beste Voraussetzungen f\u00fcr einen perfekten Filmabend. Damit Du die besten Thriller mit IMDb-Topbewertung immer schnell findest, haben wir in unseren TV-Apps und im Web-Player Genres zusammengestellt, in denen Du immer schnell findest, was Du anschauen willst. So haben wir in unserem Genre <a href=\"https:\/\/tv.teleboy.ch\/home(landingpage:themen\/thriller\/572)\">\u00abKrimi &amp; Thriller\u00bb<\/a> auch alle Empfehlungen aus diesem Artikel und viele mehr zusammengestellt. Damit steht dem n\u00e4chsten Nervenkitzel nichts mehr im Weg! <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Thriller-IMDb.png\" alt=\"\" class=\"wp-image-6205\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Thriller-IMDb.png 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Thriller-IMDb-300x200.png 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Thriller-IMDb-768x512.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Lust auf einen Adrenalinrausch? Dann wirst Du im Teleboy Genre \u00abKrimi &amp; Thriller\u00bb sicher f\u00fcndig. <\/figcaption><\/figure>\n\n\n\n<p>\u00dcber die besten Horrorfilme mit IMDb-Topbewertung liest Du <a href=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/\">in diesem Artikel.<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nervenkitzel pur: Wir pr\u00e4sentieren Dir die besten Thriller mit einer sehr guten IMDb-Bewertung.<\/p>\n","protected":false},"author":12,"featured_media":6155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"coauthors":[91],"class_list":["post-6147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv-und-streaming"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die besten Thriller mit IMDb-Topbewertung &#8211; Teleboy Magazin<\/title>\n<meta name=\"description\" content=\"Nervenkitzel pur: Das sind die besten Thriller mit IMDb-Topbewertung, die auf Deiner Watchlist nicht fehlen sollten...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die besten Thriller mit IMDb-Topbewertung\" \/>\n<meta property=\"og:description\" content=\"Nervenkitzel pur: Das sind die besten Thriller mit IMDb-Topbewertung, die auf Deiner Watchlist nicht fehlen sollten...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/\" \/>\n<meta property=\"og:site_name\" content=\"Teleboy Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teleboy.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-04T07:32:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-17T09:44:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento-2_\u00a9-Columbia-TriStar.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1221\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christopher Diekhaus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TeleboyCH\" \/>\n<meta name=\"twitter:site\" content=\"@TeleboyCH\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christopher Diekhaus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Christopher Diekhaus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/\"},\"author\":{\"name\":\"Christopher Diekhaus\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/person\\\/7b1748868c797bafa2a52b39da1e3f17\"},\"headline\":\"Die besten Thriller mit IMDb-Topbewertung\",\"datePublished\":\"2023-04-04T07:32:23+00:00\",\"dateModified\":\"2023-04-17T09:44:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/\"},\"wordCount\":1574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Memento-2_\u00a9-Columbia-TriStar.jpeg\",\"articleSection\":[\"TV &amp; Streaming\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/\",\"name\":\"Die besten Thriller mit IMDb-Topbewertung &#8211; Teleboy Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Memento-2_\u00a9-Columbia-TriStar.jpeg\",\"datePublished\":\"2023-04-04T07:32:23+00:00\",\"dateModified\":\"2023-04-17T09:44:01+00:00\",\"description\":\"Nervenkitzel pur: Das sind die besten Thriller mit IMDb-Topbewertung, die auf Deiner Watchlist nicht fehlen sollten...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Memento-2_\u00a9-Columbia-TriStar.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Memento-2_\u00a9-Columbia-TriStar.jpeg\",\"width\":1221,\"height\":738,\"caption\":\"Die besten Thriller mit IMDb-Topbewertung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-thriller-mit-imdb-topbewertung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die besten Thriller mit IMDb-Topbewertung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\",\"name\":\"Teleboy Magazin\",\"description\":\"News, Tipps und Unterhaltung rund um Teleboy und Telekommunikation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\",\"name\":\"Teleboy\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/10.21.3.18\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Teleboy-Logo-gross.jpg\",\"contentUrl\":\"https:\\\/\\\/10.21.3.18\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Teleboy-Logo-gross.jpg\",\"width\":500,\"height\":500,\"caption\":\"Teleboy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/teleboy.ch\",\"https:\\\/\\\/x.com\\\/TeleboyCH\",\"https:\\\/\\\/www.instagram.com\\\/teleboy.ch\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/person\\\/7b1748868c797bafa2a52b39da1e3f17\",\"name\":\"Christopher Diekhaus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g2809d31bab3b8137d13c7239e3c0664a\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g\",\"caption\":\"Christopher Diekhaus\"},\"description\":\"1985 geboren. War fr\u00fcher f\u00fcr eine Filmproduktionsfirma t\u00e4tig. Arbeitet nun als Drehbuchautor und Filmkritiker in K\u00f6ln.\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/author\\\/christopher-diekhaus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die besten Thriller mit IMDb-Topbewertung &#8211; Teleboy Magazin","description":"Nervenkitzel pur: Das sind die besten Thriller mit IMDb-Topbewertung, die auf Deiner Watchlist nicht fehlen sollten...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/","og_locale":"de_DE","og_type":"article","og_title":"Die besten Thriller mit IMDb-Topbewertung","og_description":"Nervenkitzel pur: Das sind die besten Thriller mit IMDb-Topbewertung, die auf Deiner Watchlist nicht fehlen sollten...","og_url":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/","og_site_name":"Teleboy Magazin","article_publisher":"https:\/\/www.facebook.com\/teleboy.ch","article_published_time":"2023-04-04T07:32:23+00:00","article_modified_time":"2023-04-17T09:44:01+00:00","og_image":[{"width":1221,"height":738,"url":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento-2_\u00a9-Columbia-TriStar.jpeg","type":"image\/jpeg"}],"author":"Christopher Diekhaus","twitter_card":"summary_large_image","twitter_creator":"@TeleboyCH","twitter_site":"@TeleboyCH","twitter_misc":{"Geschrieben von":"Christopher Diekhaus","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten","Written by":"Christopher Diekhaus"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#article","isPartOf":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/"},"author":{"name":"Christopher Diekhaus","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/person\/7b1748868c797bafa2a52b39da1e3f17"},"headline":"Die besten Thriller mit IMDb-Topbewertung","datePublished":"2023-04-04T07:32:23+00:00","dateModified":"2023-04-17T09:44:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/"},"wordCount":1574,"commentCount":0,"publisher":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento-2_\u00a9-Columbia-TriStar.jpeg","articleSection":["TV &amp; Streaming"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/","url":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/","name":"Die besten Thriller mit IMDb-Topbewertung &#8211; Teleboy Magazin","isPartOf":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#primaryimage"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento-2_\u00a9-Columbia-TriStar.jpeg","datePublished":"2023-04-04T07:32:23+00:00","dateModified":"2023-04-17T09:44:01+00:00","description":"Nervenkitzel pur: Das sind die besten Thriller mit IMDb-Topbewertung, die auf Deiner Watchlist nicht fehlen sollten...","breadcrumb":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#primaryimage","url":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento-2_\u00a9-Columbia-TriStar.jpeg","contentUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/04\/Memento-2_\u00a9-Columbia-TriStar.jpeg","width":1221,"height":738,"caption":"Die besten Thriller mit IMDb-Topbewertung"},{"@type":"BreadcrumbList","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-thriller-mit-imdb-topbewertung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.teleboy.ch\/magazin\/"},{"@type":"ListItem","position":2,"name":"Die besten Thriller mit IMDb-Topbewertung"}]},{"@type":"WebSite","@id":"https:\/\/www.teleboy.ch\/magazin\/#website","url":"https:\/\/www.teleboy.ch\/magazin\/","name":"Teleboy Magazin","description":"News, Tipps und Unterhaltung rund um Teleboy und Telekommunikation","publisher":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teleboy.ch\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.teleboy.ch\/magazin\/#organization","name":"Teleboy","url":"https:\/\/www.teleboy.ch\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/10.21.3.18\/magazin\/wp-content\/uploads\/2021\/09\/Teleboy-Logo-gross.jpg","contentUrl":"https:\/\/10.21.3.18\/magazin\/wp-content\/uploads\/2021\/09\/Teleboy-Logo-gross.jpg","width":500,"height":500,"caption":"Teleboy"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teleboy.ch","https:\/\/x.com\/TeleboyCH","https:\/\/www.instagram.com\/teleboy.ch\/"]},{"@type":"Person","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/person\/7b1748868c797bafa2a52b39da1e3f17","name":"Christopher Diekhaus","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g2809d31bab3b8137d13c7239e3c0664a","url":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g","caption":"Christopher Diekhaus"},"description":"1985 geboren. War fr\u00fcher f\u00fcr eine Filmproduktionsfirma t\u00e4tig. Arbeitet nun als Drehbuchautor und Filmkritiker in K\u00f6ln.","url":"https:\/\/www.teleboy.ch\/magazin\/author\/christopher-diekhaus\/"}]}},"_links":{"self":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/6147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/comments?post=6147"}],"version-history":[{"count":12,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/6147\/revisions"}],"predecessor-version":[{"id":6206,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/6147\/revisions\/6206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/media\/6155"}],"wp:attachment":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/media?parent=6147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/categories?post=6147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/tags?post=6147"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/coauthors?post=6147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}