{"id":6036,"date":"2023-02-21T08:50:23","date_gmt":"2023-02-21T08:50:23","guid":{"rendered":"https:\/\/www.teleboy.ch\/magazin\/?p=6036"},"modified":"2023-03-20T12:49:47","modified_gmt":"2023-03-20T12:49:47","slug":"die-besten-horrorfilme-mit-imdb-topbewertung","status":"publish","type":"post","link":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/","title":{"rendered":"Die besten Horrorfilme mit IMDb-Topbewertung"},"content":{"rendered":"\n<p><strong>Auch wenn das Horrorgenre seit jeher im Ruf steht, minderwertig zu sein, hat es \u00fcber die Jahre einige echte Meisterwerke hervorgebracht. Filme, die raffiniert mit unseren \u00c4ngsten spielen und die Abgr\u00fcnde unserer Gesellschaft sezieren. Nachfolgend pr\u00e4sentieren wir euch die besten Horrorfilme, die auf dem Portal IMDb mit besonders hohen Zuschauerbewertungen auftrumpfen k\u00f6nnen.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-nosferatu-eine-symphonie-des-grauens-1922-wegbereiter-des-vampirhorrors\"><strong>\u00abNosferatu, eine Symphonie des Grauens\u00bb (1922): Wegbereiter des Vampirhorrors<\/strong><\/h2>\n\n\n\n<p>Dreistigkeit darf man Drehbuchautor Henrik Galeen und Regisseur Friedrich Wilhelm Murnau durchaus vorwerfen. Immerhin bedienten sie sich f\u00fcr ihren Vampirfilm \u00abNosferatu, eine Symphonie des Grauens\u00bb ausgiebig an Bram Stokers Literaturklassiker \u00abDracula\u00bb, ohne sich die Rechte daran gesichert zu haben. F\u00fcr das Horrorgenre war dieser Diebstahl geistigen Eigentums allerdings ein Gl\u00fccksfall, entstand so doch eines der Meisterwerke des deutschen Kinoexpressionismus, das Filmemacher bis in die heutige Zeit loben und als grosses Vorbild nennen. <\/p>\n\n\n\n<p>Erz\u00e4hlt wird von einem jungen Mann (Gustav von Wangenheim), der einen Hauskauf mit einem Grafen namens Orlok (Max Schreck) abwickeln soll, bei dem es sich um einen Leid und Tod bringenden Blutsauger handelt. Unbehagen bereiten schon das raubtierhafte Aussehen Schrecks und die betont schummrige Lichtsetzung. Spannend ist aus r\u00fcckblickender Perspektive aber auch, wie der Gruselstreifen ein schauerliches Stimmungsbild der Weimarer Republik entwirft: Dunkle M\u00e4chte dringen in die Mitte der Gesellschaft ein und setzen sich dort fest. Mit einer IMDb-Wertung von<a href=\"https:\/\/www.imdb.com\/title\/tt0013442\/?ref_=nv_sr_srsg_0\"> 7,9 Sternen<\/a> darf sich der Vampir-Klassiker zurecht zu den besten Horrorfilmen gesellen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"674\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Nosferatur_\u00a9-Transitfilm--1024x674.jpeg\" alt=\"\" class=\"wp-image-6048\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Nosferatur_\u00a9-Transitfilm--1024x674.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Nosferatur_\u00a9-Transitfilm--300x198.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Nosferatur_\u00a9-Transitfilm--768x506.jpeg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Nosferatur_\u00a9-Transitfilm-.jpeg 1037w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ein Klassiker im Horror-Genre: \u00abNosferatu\u00bb. \u00a9Transitfilm<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-der-exorzist-1973-horror-als-kassenschlager\"><strong>\u00abDer Exorzist\u00bb (1973): Horror als Kassenschlager<\/strong><\/h2>\n\n\n\n<p>Oft wird der Horrorfilm als Genre f\u00fcr ein Nischenpublikum beschrieben. Im Fall von William Friedkins \u00abDer Exorzist\u00bb von 1973 schlug ein Gruselstreifen aber erstmals ein wie eine Bombe. Basierend auf William Peter Blattys gleichnamigem Roman, schildert die Adaption die mitreissende, furchterregende Geschichte einer Teufelsaustreibung nach wahren Begebenheiten. Glaube und Fortschritt prallen hier auf unnachahmliche Weise aufeinander. Der Tonspur kommt f\u00fcr das erzeugte Grauen eine besondere Bedeutung zu. Und der Herausforderungen liebende Friedkin scheut nicht vor Geschmacklosigkeiten zur\u00fcck, die zur Zeit der Ver\u00f6ffentlichung f\u00fcr hitzige Diskussionen sorgten. Dass wir auch 50 Jahre nach Erscheinen dieses Besessenheitsklassikers noch immer \u00fcber ihn sprechen, hat seinen Grund: Er ist, wie auch die starke IMDb-Bewertung von <a href=\"https:\/\/www.imdb.com\/title\/tt0070047\/?ref_=nv_sr_srsg_0\">8,1 Sternen<\/a> unterstreicht, einfach verdammt effektiv.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.-1-1.jpeg\" alt=\"\" class=\"wp-image-6049\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.-1-1.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.-1-1-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.-1-1-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00abDer Exorzist\u00bb geh\u00f6rt sicher zu den besten Horrorfilmen aller Zeiten. \u00a9Warner Bros.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-alien-1979-die-angst-vor-dem-fremden\"><strong>\u00abAlien\u00bb (1979): Die Angst vor dem Fremden<\/strong><\/h2>\n\n\n\n<p>Seinen Platz in der Filmgeschichte der besten Horrorfilme hat sich der um eine ausserirdische Bedrohung an Bord eines Raumfrachters drehende Angstmacher \u00abAlien\u00bb gleich in mehrfacher Hinsicht verdient. Die von Sigourney Weaver mit der richtigen Mischung aus Verletzlichkeit und Entschlossenheit gespielte Ellen Ripley ist eine der ersten grossen Actionheldinnen der Leinwand und ebnete den Weg f\u00fcr weitere Frauen in zupackenden Rollen. Wie langweilig w\u00e4re es gewesen, wenn \u2013 so war es urspr\u00fcnglich geplant \u2013 wieder einmal ein Mann im Zentrum der Handlung gestanden und sich dem titelgebenden Alien in den Weg geworfen h\u00e4tte!? <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ridley Scotts zweite Regiearbeit ist auch deshalb unvergessen, weil sie nahezu in Perfektion vorf\u00fchrt, wie man Spannung aufbaut. Viel Zeit investiert der Scifi-Schocker darin, den Zuschauer in das Setting und die Lage der Figuren einzuf\u00fchren. Erst in der zweiten H\u00e4lfte wird das Grauen konkreter, wobei vor allem die sogenannte Chestburster-Szene haften bleibt, in der dem titelgebenden Killerwesen der Sprung aus einem Wirtsk\u00f6rper gelingt. Zur unheimlichen Wirkung tragen sicher auch das von HG Giger entworfene Alien und das beklemmende Szenenbild des mit sexuellen Konnotationen aufgeladenen \u00dcberlebenskampfes bei. Mit einer IMDb-Wertung von <a href=\"https:\/\/www.imdb.com\/title\/tt0078748\/?ref_=nv_sr_srsg_0\">8,5 Sternen<\/a> geh\u00f6rt der Film zu den Top-Filmen bei IMDb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Alien_Cineman.jpeg\" alt=\"\" class=\"wp-image-6050\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Alien_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Alien_Cineman-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Alien_Cineman-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sigourney Weaver in \u00abAlien\u00bb. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-das-ding-aus-einer-anderen-welt-1982-ein-kreatives-splatter-fest\"><strong>\u00abDas Ding aus einer anderen Welt\u00bb (1982): Ein kreatives Splatter-Fest<\/strong><\/h2>\n\n\n\n<p>Und noch einmal John Carpenter! In \u00abDas Ding aus einer anderen Welt\u00bb, einem Scifi-Horrorfilm, der auf einer Kurzgeschichte beruht, erzeugt der Gruselspezialist eine \u00e4hnlich nervenaufreibende und klaustrophobische Stimmung wie sein Kollege Ridley Scott in \u00abAlien\u00bb. Handlungsort ist hier nicht ein Raumschiff, sondern eine Forschungsstation in der Antarktis, die von einem parasit\u00e4ren ausserirdischen Monster heimgesucht wird. <\/p>\n\n\n\n<p>Ber\u00fchmt ist der kammerspielartige Film vor allem wegen seiner ausgefallenen handgemachten Spezialeffekte. Wie hier K\u00f6rper aufplatzen und sich grotesk verformen, hatte man bis dato in einer Hollywood-Produktion noch nicht gesehen. F\u00fcr Carpenter lieferte Maskenk\u00fcnstler Rob Bottin wom\u00f6glich seine eindrucksvollste Arbeit ab. Honoriert wurde sie von Kritik und Publikum kurz nach Erscheinen allerdings nur wenig. Vielleicht passte die harte Gangart einfach nicht ins Jahr 1982, in dem mit E.T. der wohl knuffigste Alien der Filmgeschichte die Leinw\u00e4nde eroberte. Einer der besten Horrorfilme mit einer IMDb-Bewertung von <a href=\"https:\/\/www.imdb.com\/title\/tt0084787\/?ref_=nv_sr_srsg_0\">8,2 Sternen<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Das-Ding-aus-einer-anderen-Welt_Cineman.jpeg\" alt=\"\" class=\"wp-image-6051\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Das-Ding-aus-einer-anderen-Welt_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Das-Ding-aus-einer-anderen-Welt_Cineman-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Das-Ding-aus-einer-anderen-Welt_Cineman-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Mit einer IMDb-Bewertug von 8,2 Sternen ein erstklassiger Horrorfilm. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-shaun-of-the-dead-2004-knackige-parodie-auf-das-zombiegenre\"><strong>\u00abShaun of the Dead\u00bb (2004): Knackige Parodie auf das Zombiegenre<\/strong><\/h2>\n\n\n\n<p>Mittlerweile sind sie l\u00e4ngst zu einem Klischeemotiv geworden. Vor rund 20 Jahren waren Zombies aber noch nicht so omnipr\u00e4sent wie heute. Bereits damals legte Popkulturkenner Edgar Wright eine zitatreiche Persiflage auf das durch George A. Romeros \u00abDie Nacht der lebenden Toten\u00bb (1968) begr\u00fcndete Subgenre vor. Im Zentrum: ein Loser (Simon Pegg), wie er im Buche steht, der nach Ausbruch einer Zombie-Apokalypse mit einigen Vertrauten Zuflucht in seinem Lieblingspub sucht. <\/p>\n\n\n\n<p>\u00abShaun of the Dead\u00bb ist keine platte, von einer \u00fcberdrehten Angriffsszene zur n\u00e4chsten springende Nummernrevue, sondern spielt raffiniert mit Versatzst\u00fccken und gibt die schr\u00e4gen Hauptfiguren nicht der L\u00e4cherlichkeit preis, obwohl ihr teilweise unbeholfenes Verhalten f\u00fcr so manchen Lacher sorgt. Dank einer IMDb-Bewertung von <a href=\"https:\/\/www.imdb.com\/title\/tt0365748\/?ref_=nv_sr_srsg_0\">7,9 Sternen<\/a> hat sich auch dieser Streifen einen Platz in der Liste der besten Horrorfilme verdient.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Shaun-of-the-Dead_Cineman.jpeg\" alt=\"\" class=\"wp-image-6052\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Shaun-of-the-Dead_Cineman.jpeg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Shaun-of-the-Dead_Cineman-300x200.jpeg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Shaun-of-the-Dead_Cineman-768x512.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Horror kann auch urkomisch sein. \u00a9Cineman<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-die-besten-horrorfilme-mit-imdb-topbewertung-bei-teleboy\">Die besten Horrorfilme mit IMDb-Topbewertung bei Teleboy<\/h2>\n\n\n\n<p>Neben vielen spannenden Themenwelten findest Du bei Teleboy auch die Genre, in denen es viele Filme und Serien zu entdecken gibt. So haben wir auch ein <a href=\"https:\/\/tv.teleboy.ch\/home(landingpage:themen\/horror\/559)\">Horror-Genre<\/a>, in denen Du alle Filme aus diesem Artikel sowie viele weitere findest. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Bildschirmfoto-2023-02-21-um-09.18.34-1024x576.png\" alt=\"Horror-Filme bei Teleboy\" class=\"wp-image-6054\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Bildschirmfoto-2023-02-21-um-09.18.34-1024x576.png 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Bildschirmfoto-2023-02-21-um-09.18.34-300x169.png 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Bildschirmfoto-2023-02-21-um-09.18.34-768x432.png 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Bildschirmfoto-2023-02-21-um-09.18.34.png 1179w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Das Horror-Genre bei Teleboy. <\/figcaption><\/figure>\n\n\n\n<p>Noch mehr von den besten Horrorfilmen mit IMDb-Topbewertung liest Du bei <a href=\"https:\/\/www.cineman.ch\/article\/hoch-im-kurs-die-besten-horrorfilme-aller-zeiten\">Cineman<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Artikel liest Du \u00fcber erstklassige Horrorfilme, die sich eine IMDb-Topbewertung verdient haben.<\/p>\n","protected":false},"author":12,"featured_media":6046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"coauthors":[91],"class_list":["post-6036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv-und-streaming"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die besten Horrorfilme mit IMDb-Topbewertung &#8211; Teleboy Magazin<\/title>\n<meta name=\"description\" content=\"In diesem Artikel pr\u00e4sentieren wir Dir die besten Horrorfilme mit einer IMDb-Topbewertung. Jetzt reinlesen:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die besten Horrorfilme mit IMDb-Topbewertung\" \/>\n<meta property=\"og:description\" content=\"In diesem Artikel pr\u00e4sentieren wir Dir die besten Horrorfilme mit einer IMDb-Topbewertung. Jetzt reinlesen:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/\" \/>\n<meta property=\"og:site_name\" content=\"Teleboy Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teleboy.ch\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T08:50:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T12:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christopher Diekhaus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TeleboyCH\" \/>\n<meta name=\"twitter:site\" content=\"@TeleboyCH\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christopher Diekhaus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Christopher Diekhaus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/\"},\"author\":{\"name\":\"Christopher Diekhaus\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/person\\\/7b1748868c797bafa2a52b39da1e3f17\"},\"headline\":\"Die besten Horrorfilme mit IMDb-Topbewertung\",\"datePublished\":\"2023-02-21T08:50:23+00:00\",\"dateModified\":\"2023-03-20T12:49:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/\"},\"wordCount\":965,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Der-Exorzist_\u00a9Warner-Bros.jpeg\",\"articleSection\":[\"TV &amp; Streaming\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/\",\"name\":\"Die besten Horrorfilme mit IMDb-Topbewertung &#8211; Teleboy Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Der-Exorzist_\u00a9Warner-Bros.jpeg\",\"datePublished\":\"2023-02-21T08:50:23+00:00\",\"dateModified\":\"2023-03-20T12:49:47+00:00\",\"description\":\"In diesem Artikel pr\u00e4sentieren wir Dir die besten Horrorfilme mit einer IMDb-Topbewertung. Jetzt reinlesen:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Der-Exorzist_\u00a9Warner-Bros.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Der-Exorzist_\u00a9Warner-Bros.jpeg\",\"width\":1200,\"height\":801,\"caption\":\"Die besten Horrorfilme\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/die-besten-horrorfilme-mit-imdb-topbewertung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die besten Horrorfilme mit IMDb-Topbewertung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\",\"name\":\"Teleboy Magazin\",\"description\":\"News, Tipps und Unterhaltung rund um Teleboy und Telekommunikation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\",\"name\":\"Teleboy\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/10.21.3.18\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Teleboy-Logo-gross.jpg\",\"contentUrl\":\"https:\\\/\\\/10.21.3.18\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Teleboy-Logo-gross.jpg\",\"width\":500,\"height\":500,\"caption\":\"Teleboy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/teleboy.ch\",\"https:\\\/\\\/x.com\\\/TeleboyCH\",\"https:\\\/\\\/www.instagram.com\\\/teleboy.ch\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/person\\\/7b1748868c797bafa2a52b39da1e3f17\",\"name\":\"Christopher Diekhaus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g2809d31bab3b8137d13c7239e3c0664a\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g\",\"caption\":\"Christopher Diekhaus\"},\"description\":\"1985 geboren. War fr\u00fcher f\u00fcr eine Filmproduktionsfirma t\u00e4tig. Arbeitet nun als Drehbuchautor und Filmkritiker in K\u00f6ln.\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/author\\\/christopher-diekhaus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die besten Horrorfilme mit IMDb-Topbewertung &#8211; Teleboy Magazin","description":"In diesem Artikel pr\u00e4sentieren wir Dir die besten Horrorfilme mit einer IMDb-Topbewertung. Jetzt reinlesen:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/","og_locale":"de_DE","og_type":"article","og_title":"Die besten Horrorfilme mit IMDb-Topbewertung","og_description":"In diesem Artikel pr\u00e4sentieren wir Dir die besten Horrorfilme mit einer IMDb-Topbewertung. Jetzt reinlesen:","og_url":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/","og_site_name":"Teleboy Magazin","article_publisher":"https:\/\/www.facebook.com\/teleboy.ch","article_published_time":"2023-02-21T08:50:23+00:00","article_modified_time":"2023-03-20T12:49:47+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.jpeg","type":"image\/jpeg"}],"author":"Christopher Diekhaus","twitter_card":"summary_large_image","twitter_creator":"@TeleboyCH","twitter_site":"@TeleboyCH","twitter_misc":{"Geschrieben von":"Christopher Diekhaus","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten","Written by":"Christopher Diekhaus"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#article","isPartOf":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/"},"author":{"name":"Christopher Diekhaus","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/person\/7b1748868c797bafa2a52b39da1e3f17"},"headline":"Die besten Horrorfilme mit IMDb-Topbewertung","datePublished":"2023-02-21T08:50:23+00:00","dateModified":"2023-03-20T12:49:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/"},"wordCount":965,"commentCount":0,"publisher":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.jpeg","articleSection":["TV &amp; Streaming"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/","url":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/","name":"Die besten Horrorfilme mit IMDb-Topbewertung &#8211; Teleboy Magazin","isPartOf":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#primaryimage"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.jpeg","datePublished":"2023-02-21T08:50:23+00:00","dateModified":"2023-03-20T12:49:47+00:00","description":"In diesem Artikel pr\u00e4sentieren wir Dir die besten Horrorfilme mit einer IMDb-Topbewertung. Jetzt reinlesen:","breadcrumb":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#primaryimage","url":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.jpeg","contentUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2023\/02\/Der-Exorzist_\u00a9Warner-Bros.jpeg","width":1200,"height":801,"caption":"Die besten Horrorfilme"},{"@type":"BreadcrumbList","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/die-besten-horrorfilme-mit-imdb-topbewertung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.teleboy.ch\/magazin\/"},{"@type":"ListItem","position":2,"name":"Die besten Horrorfilme mit IMDb-Topbewertung"}]},{"@type":"WebSite","@id":"https:\/\/www.teleboy.ch\/magazin\/#website","url":"https:\/\/www.teleboy.ch\/magazin\/","name":"Teleboy Magazin","description":"News, Tipps und Unterhaltung rund um Teleboy und Telekommunikation","publisher":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teleboy.ch\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.teleboy.ch\/magazin\/#organization","name":"Teleboy","url":"https:\/\/www.teleboy.ch\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/10.21.3.18\/magazin\/wp-content\/uploads\/2021\/09\/Teleboy-Logo-gross.jpg","contentUrl":"https:\/\/10.21.3.18\/magazin\/wp-content\/uploads\/2021\/09\/Teleboy-Logo-gross.jpg","width":500,"height":500,"caption":"Teleboy"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teleboy.ch","https:\/\/x.com\/TeleboyCH","https:\/\/www.instagram.com\/teleboy.ch\/"]},{"@type":"Person","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/person\/7b1748868c797bafa2a52b39da1e3f17","name":"Christopher Diekhaus","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g2809d31bab3b8137d13c7239e3c0664a","url":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g","caption":"Christopher Diekhaus"},"description":"1985 geboren. War fr\u00fcher f\u00fcr eine Filmproduktionsfirma t\u00e4tig. Arbeitet nun als Drehbuchautor und Filmkritiker in K\u00f6ln.","url":"https:\/\/www.teleboy.ch\/magazin\/author\/christopher-diekhaus\/"}]}},"_links":{"self":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/6036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/comments?post=6036"}],"version-history":[{"count":8,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/6036\/revisions"}],"predecessor-version":[{"id":6056,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/6036\/revisions\/6056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/media\/6046"}],"wp:attachment":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/media?parent=6036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/categories?post=6036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/tags?post=6036"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/coauthors?post=6036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}