{"id":3831,"date":"2021-12-15T10:41:34","date_gmt":"2021-12-15T10:41:34","guid":{"rendered":"https:\/\/blog.teleboy.ch\/?p=3831"},"modified":"2025-06-17T15:49:34","modified_gmt":"2025-06-17T15:49:34","slug":"bescheidenheit-ist-keine-zier-keanu-reeves","status":"publish","type":"post","link":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/","title":{"rendered":"Bescheidenheit ist keine Zier: Keanu Reeves"},"content":{"rendered":"\n<p>Im Filmbusiness, erst recht in der Traumfabrik Hollywood, tummeln sich nicht wenige Selbstdarsteller. Menschen, denen jede B\u00fchne recht ist. Die keine Gelegenheit auslassen, ihre Strahlkraft zu beweisen. Deren Gesichter st\u00e4ndig in den Klatschspalten erscheinen. Die auf irgendeine Weise von sich h\u00f6ren machen, selbst wenn gerade kein neuer Kinostart beworben werden muss. Dass es auch anders geht, zeigt seit vielen Jahren der Leinwandstar Keanu Reeves, der gelassen \u00fcber dem \u00fcblichen Branchenrummel zu stehen scheint: H\u00f6flich, bodenst\u00e4ndig, grossz\u00fcgig und von Skandalen frei. So nimmt die Welt den im libanesischen Beirut geborenen Kanadier mit hawaiianischen Wurzeln wahr, der sp\u00e4testens mit \u201e<a href=\"https:\/\/www.teleboy.ch\/search?query=title:speed\" target=\"_blank\" rel=\"noreferrer noopener\">Speed\u201c (1994)<\/a> international bekannt wurde und durch die kurz vor Weihnachten in eine vierte Runde gehende \u201eMatrix\u201c-Reihe echten Kultstatus erlangte.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"434\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-1024x434.jpg\" alt=\"\" class=\"wp-image-3833\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-1024x434.jpg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-300x127.jpg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-768x325.jpg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-1536x650.jpg 1536w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-2048x867.jpg 2048w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-1920x813.jpg 1920w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-1170x495.jpg 1170w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNGE3YjdmN2MtMzY1Yy00NzIzLWI4YzktYTE3N2Y4MzNjYmFhXkEyXkFqcGdeQXVyNjUxMjc1OTM@._V1_-585x248.jpg 585w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Keanu Reeves in <a href=\"https:\/\/www.teleboy.ch\/search?query=title:speed\" target=\"_blank\" rel=\"noreferrer noopener\">Speed<\/a> (1994) \u00a9&nbsp;IMDb<\/figcaption><\/figure>\n\n\n\n<p>Als Computerhacker Neo, dem unverhofft die messianische Aufgabe zuf\u00e4llt, die in einer simulierten Realit\u00e4t von Maschinen versklavte Menschheit zu retten, schrieb sich der Schauspieler 1999 mit <a href=\"https:\/\/www.teleboy.ch\/search?query=title:The%20Matrix\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eThe Matrix\u201c<\/a> in die Filmgeschichte ein. Der von den Wachowski-Schwestern (die damals noch Br\u00fcder waren) inszenierte Mix aus d\u00fcsterer Dystopie und asiatisch angehauchtem Actionkino verbindet geschickt philosophische \u00dcberlegungen, Mystik und Spektakel und bescherte dem an den Einnahmen beteiligten Reeves ein Verm\u00f6gen, das er \u2013 so ist immer wieder zu lesen \u2013 gerne in gute Zwecke investiert. &nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_-1024x577.jpg\" alt=\"\" class=\"wp-image-3834\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_-1024x577.jpg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_-300x169.jpg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_-768x433.jpg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_-1170x659.jpg 1170w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_-585x330.jpg 585w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BZTFhODU4M2ItM2IwYi00ODBjLTk2OWYtZGJlN2NkMzM1ZWZiXkEyXkFqcGdeQXVyMDI2NDg0NQ@@._V1_.jpg 1296w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Keanu Reeves in <a href=\"https:\/\/www.teleboy.ch\/search?query=title:The%20Matrix\" target=\"_blank\" rel=\"noreferrer noopener\">The Matrix<\/a> (1999) \u00a9&nbsp;Warner Brothers<\/figcaption><\/figure>\n\n\n\n<p>W\u00e4hrend ihn die Netzgemeinde seit geraumer Zeit f\u00fcr seine selbstlosen Taten und sein unpr\u00e4tenti\u00f6ses Auftreten in Memes feiert, macht er selbst wenig Aufheben darum, dass er unter anderem die Krebsforschung unterst\u00fctzt. \u00dcberhaupt h\u00e4lt sich Reeves bedeckt, wenn es um seine Person und sein Privatleben geht. Mehrere Kollegen, die mit ihm drehten, gaben zu Protokoll, dass er schweigsam, nachdenklich und schwer durchdringlich sei. \u00dcber seinen Glauben gibt er nur kryptisch Auskunft. Und seine Beziehung mit der K\u00fcnstlerin Alexandra Grant, mit der er bereits zwei B\u00fccher herausbrachte, ist f\u00fcr die \u00d6ffentlichkeit, von wenigen Auftritten auf dem roten Teppich abgesehen, tabu.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-1024x683.jpg\" alt=\"\" class=\"wp-image-3835\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-1024x683.jpg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-300x200.jpg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-768x512.jpg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-1536x1024.jpg 1536w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-1920x1280.jpg 1920w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-1170x780.jpg 1170w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-585x390.jpg 585w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_-263x175.jpg 263w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjQzMDg1NzcxNl5BMl5BanBnXkFtZTgwMDM0NzEzMDI@._V1_.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.teleboy.ch\/search?query=title:Keanu%20Reeves\" target=\"_blank\" rel=\"noreferrer noopener\">Keanu Reeves<\/a> \u00a9&nbsp;StarPix2016<\/figcaption><\/figure>\n\n\n\n<p>Wahrscheinlich h\u00e4ngt seine Zur\u00fcckhaltung auch mit den Erfahrungen nach diversen Schicksalsschl\u00e4gen zusammen, die bei einem Prominenten wie ihm teilweise breit ausgeschlachtet wurden. F\u00fcr Aufsehen im Medienzirkus sorgte etwa der Drogentod seines engen Freundes und <a href=\"https:\/\/www.teleboy.ch\/search?query=title:My%20Own%20Private%20Idaho\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eMy Own Private Idaho\u201c<\/a>-Leinwandpartners River Phoenix im Jahr 1993. Gefundene Fressen f\u00fcr den Boulevard waren zudem die Totgeburt seiner Tochter Ava im Jahr 1999 und der Verlust von Avas Mutter Jennifer Syme, die 2001, kurz nachdem sie mit Reeves wieder zusammengekommen war, bei einem Autounfall starb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"685\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWMyNDEwNzQtOGI3ZC00MGUyLTllMzQtNjA5OWU2NTA1Y2U1L2ltYWdlL2ltYWdlXkEyXkFqcGdeQXVyMTEzNzczMA@@._V1_.jpg\" alt=\"\" class=\"wp-image-3836\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWMyNDEwNzQtOGI3ZC00MGUyLTllMzQtNjA5OWU2NTA1Y2U1L2ltYWdlL2ltYWdlXkEyXkFqcGdeQXVyMTEzNzczMA@@._V1_.jpg 900w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWMyNDEwNzQtOGI3ZC00MGUyLTllMzQtNjA5OWU2NTA1Y2U1L2ltYWdlL2ltYWdlXkEyXkFqcGdeQXVyMTEzNzczMA@@._V1_-300x228.jpg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWMyNDEwNzQtOGI3ZC00MGUyLTllMzQtNjA5OWU2NTA1Y2U1L2ltYWdlL2ltYWdlXkEyXkFqcGdeQXVyMTEzNzczMA@@._V1_-768x585.jpg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWMyNDEwNzQtOGI3ZC00MGUyLTllMzQtNjA5OWU2NTA1Y2U1L2ltYWdlL2ltYWdlXkEyXkFqcGdeQXVyMTEzNzczMA@@._V1_-585x445.jpg 585w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/www.teleboy.ch\/search?query=name:River%20Phoenix\" target=\"_blank\" rel=\"noreferrer noopener\">River Phoenix<\/a>&nbsp;and&nbsp;Keanu Reeves&nbsp;in&nbsp;<a href=\"https:\/\/www.teleboy.ch\/search?query=title:Private%20Idaho\" target=\"_blank\" rel=\"noreferrer noopener\">My Own Private Idaho<\/a> (1991)<\/figcaption><\/figure>\n\n\n\n<p>Weniger schwerwiegend, aber doch zerm\u00fcrbend d\u00fcrften auch die negativen Stimmen gewesen sein, die die Karriere des Darstellers schon fr\u00fch begleiteten. Sein Spiel sei schrecklich h\u00f6lzern, bem\u00e4ngelte so mancher Kritiker. Und gleich mehrere Male wurde Reeves f\u00fcr die Goldene Himbeere, den Hollywood-Antipreis f\u00fcr die schlechtesten Leistungen des Jahres, nominiert. \u201eGewinnen\u201c konnte er ihn bislang aber nie. In seiner Filmografie gibt es fraglos einige Fehlsch\u00fcsse, beispielsweise den Serienkillerthriller <a href=\"https:\/\/www.teleboy.ch\/search?query=title:The%20Watcher\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eThe Watcher\u201c (2000)<\/a>, in dem er nur widerwillig auftrat, oder j\u00fcngst den futuristischen Spannungsstreifen <a href=\"https:\/\/www.teleboy.ch\/search?query=title:Replicas\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eReplicas\u201c (2018)<\/a>. Andererseits ist seine Rollenwahl aber erfreulich breit gef\u00e4chert. Gaga-Parts wie in <a href=\"https:\/\/www.teleboy.ch\/search?query=title:Bill%20%26%20Teds%20verr%C3%BCckte%20Reise\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eBill &amp; Teds verr\u00fcckte Reise durch die Zeit\u201c (1989)<\/a> samt Fortsetzungen finden in seiner Laufbahn Platz neben eindringlichen Dramen wie <a href=\"https:\/\/www.teleboy.ch\/search?query=title:Private%20Idaho\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eMy Own Private Idaho\u201c (1991)<\/a>, romantischen Kom\u00f6dien wie \u201eSomething\u2019s Gotta Give\u201c (2003), erfrischenden Coming-of-Age-Arbeiten wie \u201eThumbsucker\u201c (2007) und ungew\u00f6hnlichen Science-Fiction-Werken wie \u201eA Scanner Darkly\u201c (2006).&nbsp; Sein Interesse an der eigenen Kunstform Kino bekundete Reeves mit dem Dokumentarfilm \u201eSide by Side\u201c (2012), f\u00fcr den er bekannte Filmemacher interviewte und der Frage nachging, welche Ver\u00e4nderungen die digitale Technik mit sich bringt. In seiner bislang einzigen Regiearbeit <a href=\"https:\/\/www.teleboy.ch\/search?query=title:Man%20of%20Tai%20Chi\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eMan of Tai Chi\u201c (2013)<\/a> trug er seinem Martial-Arts-Interesse Rechnung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"728\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-1024x728.jpg\" alt=\"\" class=\"wp-image-3837\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-1024x728.jpg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-300x213.jpg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-768x546.jpg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-1536x1091.jpg 1536w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-1920x1364.jpg 1920w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-1170x831.jpg 1170w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_-585x416.jpg 585w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMjE5NjM4MDYzOF5BMl5BanBnXkFtZTcwNjU0NDQ1OQ@@._V1_.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Keanu Reeves&nbsp;bei einem Event f\u00fcr&nbsp;<a href=\"https:\/\/www.teleboy.ch\/search?query=title:Man%20of%20Tai%20Chi\" target=\"_blank\" rel=\"noreferrer noopener\">Man of Tai Chi<\/a> (2013) \u00a9&nbsp;Getty Images<\/figcaption><\/figure>\n\n\n\n<p>Ab Mitte der 2000er Jahre musste Reeves an den Kinokassen einige Misserfolge verkraften und schien an Starpower massiv eingeb\u00fcsst zu haben. Mit dem beinharten Unterweltthriller <a href=\"https:\/\/www.teleboy.ch\/search?query=title:John%20Wick\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eJohn Wick\u201c<\/a> sorgte er 2014 allerdings f\u00fcr Furore und stellte einmal mehr seine F\u00e4higkeiten im Actionfach unter Beweis. Die Figur des titelgebenden Ex-Auftragskillers, der die T\u00f6tung seines Hundes r\u00e4chen will, erfreut sich heute, auch dank zweier Fortsetzungen, eines gewissen Kultcharakters. Dass Reeves nun, 18 Jahre nach <a href=\"https:\/\/www.teleboy.ch\/search?query=title:Matrix%20Revolutions\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eThe Matrix Revolutions\u201c (2003)<\/a>, in seine wohl ikonischste Rolle zur\u00fcckkehrt, ist ein weiterer Beleg, dass man den bescheidenen Hollywood-Star noch l\u00e4ngst nicht abschreiben sollte. Ob er mit dem vierten Kapitel <a href=\"https:\/\/www.cineman.ch\/movie\/2021\/TheMatrix4\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201eThe Matrix Resurrections\u201c<\/a>, das Neo auf eine andere Morpheus-Version treffen l\u00e4sst und in den Kampf gegen eine neue Gefahr schickt, an den Erfolg der Vorg\u00e4nger anschliessen kann, erfahren wir ab dem 23.12. Dann, wenn es wieder heisst: Follow the white rabbit!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"671\" src=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-1024x671.jpg\" alt=\"\" class=\"wp-image-3838\" srcset=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-1024x671.jpg 1024w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-300x197.jpg 300w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-768x504.jpg 768w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-1536x1007.jpg 1536w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-2048x1343.jpg 2048w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-1920x1259.jpg 1920w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-1170x767.jpg 1170w, https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BMzMzZGQzMjktODBiNS00MzBkLWI0NjYtZDRmOGVmOWE5ZmMyXkEyXkFqcGdeQXVyMDM2NDM2MQ@@._V1_-585x384.jpg 585w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Keanu Reeves&nbsp;bei einem Event f\u00fcr&nbsp;<a href=\"https:\/\/www.teleboy.ch\/search?query=title:John%20Wick%20Kapitel%203\" target=\"_blank\" rel=\"noreferrer noopener\">John Wick: Kapitel 3<\/a> (2019) <meta charset=\"utf-8\">\u00a9&nbsp;Getty Images<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Weltstar mit vielen H\u00f6hen und Tiefen. Wir haben f\u00fcr Dich einen Blick hinter die Fassade geworfen.<\/p>\n","protected":false},"author":12,"featured_media":3832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"coauthors":[91],"class_list":["post-3831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv-und-streaming"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bescheidenheit ist keine Zier: Keanu Reeves &#8211; Teleboy Magazin<\/title>\n<meta name=\"description\" content=\"Er hat unsere Filmherzen h\u00f6her schlagen lassen als John Wick oder Neo. Aber wer steckt wirklich hinter dieser harten Fassade?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bescheidenheit ist keine Zier: Keanu Reeves\" \/>\n<meta property=\"og:description\" content=\"Er hat unsere Filmherzen h\u00f6her schlagen lassen als John Wick oder Neo. Aber wer steckt wirklich hinter dieser harten Fassade?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/\" \/>\n<meta property=\"og:site_name\" content=\"Teleboy Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teleboy.ch\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T10:41:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T15:49:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christopher Diekhaus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TeleboyCH\" \/>\n<meta name=\"twitter:site\" content=\"@TeleboyCH\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christopher Diekhaus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Christopher Diekhaus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/\"},\"author\":{\"name\":\"Christopher Diekhaus\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/person\\\/7b1748868c797bafa2a52b39da1e3f17\"},\"headline\":\"Bescheidenheit ist keine Zier: Keanu Reeves\",\"datePublished\":\"2021-12-15T10:41:34+00:00\",\"dateModified\":\"2025-06-17T15:49:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/\"},\"wordCount\":812,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg\",\"articleSection\":[\"TV &amp; Streaming\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/\",\"name\":\"Bescheidenheit ist keine Zier: Keanu Reeves &#8211; Teleboy Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg\",\"datePublished\":\"2021-12-15T10:41:34+00:00\",\"dateModified\":\"2025-06-17T15:49:34+00:00\",\"description\":\"Er hat unsere Filmherzen h\u00f6her schlagen lassen als John Wick oder Neo. Aber wer steckt wirklich hinter dieser harten Fassade?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg\",\"width\":2560,\"height\":1718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/tv-und-streaming\\\/bescheidenheit-ist-keine-zier-keanu-reeves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bescheidenheit ist keine Zier: Keanu Reeves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\",\"name\":\"Teleboy Magazin\",\"description\":\"News, Tipps und Unterhaltung rund um Teleboy und Telekommunikation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#organization\",\"name\":\"Teleboy\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/10.21.3.18\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Teleboy-Logo-gross.jpg\",\"contentUrl\":\"https:\\\/\\\/10.21.3.18\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Teleboy-Logo-gross.jpg\",\"width\":500,\"height\":500,\"caption\":\"Teleboy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/teleboy.ch\",\"https:\\\/\\\/x.com\\\/TeleboyCH\",\"https:\\\/\\\/www.instagram.com\\\/teleboy.ch\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/#\\\/schema\\\/person\\\/7b1748868c797bafa2a52b39da1e3f17\",\"name\":\"Christopher Diekhaus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g2809d31bab3b8137d13c7239e3c0664a\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g\",\"caption\":\"Christopher Diekhaus\"},\"description\":\"1985 geboren. War fr\u00fcher f\u00fcr eine Filmproduktionsfirma t\u00e4tig. Arbeitet nun als Drehbuchautor und Filmkritiker in K\u00f6ln.\",\"url\":\"https:\\\/\\\/www.teleboy.ch\\\/magazin\\\/author\\\/christopher-diekhaus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bescheidenheit ist keine Zier: Keanu Reeves &#8211; Teleboy Magazin","description":"Er hat unsere Filmherzen h\u00f6her schlagen lassen als John Wick oder Neo. Aber wer steckt wirklich hinter dieser harten Fassade?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/","og_locale":"de_DE","og_type":"article","og_title":"Bescheidenheit ist keine Zier: Keanu Reeves","og_description":"Er hat unsere Filmherzen h\u00f6her schlagen lassen als John Wick oder Neo. Aber wer steckt wirklich hinter dieser harten Fassade?","og_url":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/","og_site_name":"Teleboy Magazin","article_publisher":"https:\/\/www.facebook.com\/teleboy.ch","article_published_time":"2021-12-15T10:41:34+00:00","article_modified_time":"2025-06-17T15:49:34+00:00","og_image":[{"width":2560,"height":1718,"url":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg","type":"image\/jpeg"}],"author":"Christopher Diekhaus","twitter_card":"summary_large_image","twitter_creator":"@TeleboyCH","twitter_site":"@TeleboyCH","twitter_misc":{"Geschrieben von":"Christopher Diekhaus","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten","Written by":"Christopher Diekhaus"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#article","isPartOf":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/"},"author":{"name":"Christopher Diekhaus","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/person\/7b1748868c797bafa2a52b39da1e3f17"},"headline":"Bescheidenheit ist keine Zier: Keanu Reeves","datePublished":"2021-12-15T10:41:34+00:00","dateModified":"2025-06-17T15:49:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/"},"wordCount":812,"commentCount":0,"publisher":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg","articleSection":["TV &amp; Streaming"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/","url":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/","name":"Bescheidenheit ist keine Zier: Keanu Reeves &#8211; Teleboy Magazin","isPartOf":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#primaryimage"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#primaryimage"},"thumbnailUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg","datePublished":"2021-12-15T10:41:34+00:00","dateModified":"2025-06-17T15:49:34+00:00","description":"Er hat unsere Filmherzen h\u00f6her schlagen lassen als John Wick oder Neo. Aber wer steckt wirklich hinter dieser harten Fassade?","breadcrumb":{"@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#primaryimage","url":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg","contentUrl":"https:\/\/www.teleboy.ch\/magazin\/wp-content\/uploads\/2021\/12\/MV5BNWZkMWE1YTMtY2NlZS00MjQxLWJkMmEtMjMyN2I4N2Q5YzllXkEyXkFqcGdeQXVyMTkxNjUyNQ@@._V1_-scaled.jpg","width":2560,"height":1718},{"@type":"BreadcrumbList","@id":"https:\/\/www.teleboy.ch\/magazin\/tv-und-streaming\/bescheidenheit-ist-keine-zier-keanu-reeves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.teleboy.ch\/magazin\/"},{"@type":"ListItem","position":2,"name":"Bescheidenheit ist keine Zier: Keanu Reeves"}]},{"@type":"WebSite","@id":"https:\/\/www.teleboy.ch\/magazin\/#website","url":"https:\/\/www.teleboy.ch\/magazin\/","name":"Teleboy Magazin","description":"News, Tipps und Unterhaltung rund um Teleboy und Telekommunikation","publisher":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teleboy.ch\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.teleboy.ch\/magazin\/#organization","name":"Teleboy","url":"https:\/\/www.teleboy.ch\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/10.21.3.18\/magazin\/wp-content\/uploads\/2021\/09\/Teleboy-Logo-gross.jpg","contentUrl":"https:\/\/10.21.3.18\/magazin\/wp-content\/uploads\/2021\/09\/Teleboy-Logo-gross.jpg","width":500,"height":500,"caption":"Teleboy"},"image":{"@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teleboy.ch","https:\/\/x.com\/TeleboyCH","https:\/\/www.instagram.com\/teleboy.ch\/"]},{"@type":"Person","@id":"https:\/\/www.teleboy.ch\/magazin\/#\/schema\/person\/7b1748868c797bafa2a52b39da1e3f17","name":"Christopher Diekhaus","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g2809d31bab3b8137d13c7239e3c0664a","url":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1be7b36eda983b9e9b01e8ebe085b1901cf122340bfbef7e3e6612d5cea5c9df?s=96&d=mm&r=g","caption":"Christopher Diekhaus"},"description":"1985 geboren. War fr\u00fcher f\u00fcr eine Filmproduktionsfirma t\u00e4tig. Arbeitet nun als Drehbuchautor und Filmkritiker in K\u00f6ln.","url":"https:\/\/www.teleboy.ch\/magazin\/author\/christopher-diekhaus\/"}]}},"_links":{"self":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/3831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/comments?post=3831"}],"version-history":[{"count":6,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/3831\/revisions"}],"predecessor-version":[{"id":5834,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/posts\/3831\/revisions\/5834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/media\/3832"}],"wp:attachment":[{"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/media?parent=3831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/categories?post=3831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/tags?post=3831"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.teleboy.ch\/magazin\/wp-json\/wp\/v2\/coauthors?post=3831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}